{"id":10686,"date":"2026-06-25T00:39:26","date_gmt":"2026-06-24T22:39:26","guid":{"rendered":"https:\/\/cdtt91.fr\/?p=10686"},"modified":"2026-06-25T00:39:27","modified_gmt":"2026-06-24T22:39:27","slug":"calendrier-2026-2027","status":"publish","type":"post","link":"https:\/\/cdtt91.fr\/index.php\/2026\/06\/25\/calendrier-2026-2027\/","title":{"rendered":"Calendrier 2026 2027"},"content":{"rendered":"<div class=\"post-content\">\n<p>V2 : Placement des comp\u00e9titions d\u00e9partementales, d\u00e9calage de la J1 Ph1, modification de la date du CF T4<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/cdtt91.fr\/wp-content\/uploads\/2026\/03\/Calendrier-DEP-2026-2027_V2-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Calendrier DEP 2026-2027_V2.\"><\/object><a id=\"wp-block-file--media-07a8a19a-634c-4a08-a10b-5f7d3e2885b8\" href=\"https:\/\/cdtt91.fr\/wp-content\/uploads\/2026\/03\/Calendrier-DEP-2026-2027_V2-1.pdf\">Calendrier DEP 2026-2027_V2<\/a><a href=\"https:\/\/cdtt91.fr\/wp-content\/uploads\/2026\/03\/Calendrier-DEP-2026-2027_V2-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-07a8a19a-634c-4a08-a10b-5f7d3e2885b8\">T\u00e9l\u00e9charger<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>V2 : Placement des comp\u00e9titions d\u00e9partementales, d\u00e9calage de la J1<a href=\"https:\/\/cdtt91.fr\/index.php\/2026\/06\/25\/calendrier-2026-2027\/\">Plus de d\u00e9tails<i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i><\/a><\/p>\n","protected":false},"author":4,"featured_media":8762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/posts\/10686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/comments?post=10686"}],"version-history":[{"count":3,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/posts\/10686\/revisions"}],"predecessor-version":[{"id":11291,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/posts\/10686\/revisions\/11291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/media\/8762"}],"wp:attachment":[{"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/media?parent=10686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/categories?post=10686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdtt91.fr\/index.php\/wp-json\/wp\/v2\/tags?post=10686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}